{"id":563,"date":"2023-03-03T11:16:31","date_gmt":"2023-03-03T09:16:31","guid":{"rendered":"https:\/\/fedalcyta.org\/wp\/?p=563"},"modified":"2023-09-28T16:20:31","modified_gmt":"2023-09-28T14:20:31","slug":"ciencia-y-tecnologia-de-los-alimentos-ahora-tambien-en-eemm-de-la-junta-de-extremadura","status":"publish","type":"post","link":"https:\/\/fedalcyta.org\/wp\/2023\/03\/03\/ciencia-y-tecnologia-de-los-alimentos-ahora-tambien-en-eemm-de-la-junta-de-extremadura\/","title":{"rendered":"Ciencia y Tecnolog\u00eda de los Alimentos, ahora tambi\u00e9n en EEMM de la Junta de Extremadura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El pasado 2 de marzo, el <a href=\"http:\/\/doe.juntaex.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Diario Oficial de Extremadura<\/a> actualizaba el listado de titulaciones que pueden acceder a cuerpos docentes de Ense\u00f1anzas Medias (EEMM) y Formaci\u00f3n Profesional (FP).<\/p>\n\n\n\n<p class=\"has-vivid-purple-color has-text-color wp-block-paragraph\">En la <a rel=\"noreferrer noopener\" href=\"http:\/\/doe.juntaex.es\/pdfs\/doe\/2023\/420o\/23060688.pdf\" target=\"_blank\">resoluci\u00f3n de 22 de febrero de 2023 (2023060688<\/a>) se incluye la titulaci\u00f3n de <strong>Ciencia y Tecnolog\u00eda de los Alimentos<\/strong> en las especialidades de <strong>F\u00edsica y Qu\u00edmica<\/strong>, <strong>Biolog\u00eda y Geolog\u00eda<\/strong> adem\u00e1s de varias dentro de FP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, una buena noticia tras el trabajo conjunto realizado por la federaci\u00f3n y ACYTAEX.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 2 de marzo, el Diario Oficial de Extremadura actualizaba el listado de titulaciones que pueden acceder a cuerpos docentes de Ense\u00f1anzas Medias (EEMM) y Formaci\u00f3n Profesional (FP). En la resoluci\u00f3n de 22 de febrero de 2023 (2023060688) se incluye la titulaci\u00f3n de Ciencia y Tecnolog\u00eda de los Alimentos en las especialidades de F\u00edsica &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fedalcyta.org\/wp\/2023\/03\/03\/ciencia-y-tecnologia-de-los-alimentos-ahora-tambien-en-eemm-de-la-junta-de-extremadura\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCiencia y Tecnolog\u00eda de los Alimentos, ahora tambi\u00e9n en EEMM de la Junta de Extremadura\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-563","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/posts\/563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/comments?post=563"}],"version-history":[{"count":1,"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/posts\/563\/revisions"}],"predecessor-version":[{"id":564,"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/posts\/563\/revisions\/564"}],"wp:attachment":[{"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/media?parent=563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/categories?post=563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fedalcyta.org\/wp\/wp-json\/wp\/v2\/tags?post=563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}